{"id":32422,"date":"2026-07-14T20:53:03","date_gmt":"2026-07-15T02:53:03","guid":{"rendered":"https:\/\/sientetupasion.com\/?p=32422"},"modified":"2026-07-14T20:53:03","modified_gmt":"2026-07-15T02:53:03","slug":"gobierno-de-trancoso-acompana-graduacion-de-la-escuela-primaria-luis-moya","status":"publish","type":"post","link":"https:\/\/sientetupasion.com\/index.php\/2026\/07\/14\/gobierno-de-trancoso-acompana-graduacion-de-la-escuela-primaria-luis-moya\/","title":{"rendered":"Gobierno de Trancoso acompa\u00f1a graduaci\u00f3n de la Escuela Primaria Luis Moya"},"content":{"rendered":"<h1><\/h1>\n<p class=\"isSelectedEnd\"><strong>Trancoso, Zacatecas.<\/strong> El Gobierno Municipal de Trancoso particip\u00f3 en la ceremonia de graduaci\u00f3n de la <strong>Escuela Primaria Luis Moya<\/strong>, donde autoridades del <strong>Departamento de Educaci\u00f3n<\/strong> acompa\u00f1aron a las y los estudiantes que concluyeron una importante etapa de su formaci\u00f3n acad\u00e9mica.<\/p>\n<p class=\"isSelectedEnd\">Durante el evento, los representantes municipales agradecieron la invitaci\u00f3n realizada por la comunidad educativa para ser parte de esta significativa celebraci\u00f3n, en la que alumnas y alumnos recibieron el reconocimiento por haber culminado con \u00e9xito su educaci\u00f3n primaria.<\/p>\n<p class=\"isSelectedEnd\">Asimismo, felicitaron a las y los egresados por el esfuerzo y la dedicaci\u00f3n demostrados a lo largo de estos a\u00f1os de estudio, destacando tambi\u00e9n el compromiso de madres y padres de familia, as\u00ed como la labor de las y los docentes, quienes contribuyeron de manera fundamental a la formaci\u00f3n de las nuevas generaciones.<\/p>\n<p class=\"isSelectedEnd\">El Gobierno Municipal expres\u00f3 sus mejores deseos a las y los graduados en el inicio de la siguiente etapa de su vida escolar, exhort\u00e1ndolos a continuar prepar\u00e1ndose con entusiasmo, disciplina y perseverancia para alcanzar sus metas personales y profesionales.<\/p>\n<p>Con estas acciones, el Ayuntamiento de Trancoso refrenda su compromiso con la educaci\u00f3n y con el acompa\u00f1amiento a las instituciones educativas, reconociendo que la preparaci\u00f3n acad\u00e9mica es la base para el desarrollo de la ni\u00f1ez y juventud del municipio.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Trancoso, Zacatecas. El Gobierno Municipal de Trancoso particip\u00f3 en la ceremonia de graduaci\u00f3n de la Escuela Primaria Luis Moya, donde autoridades del Departamento de Educaci\u00f3n acompa\u00f1aron<span class=\"excerpt-hellip\"> [\u2026]<\/span><\/p>\n","protected":false},"author":2,"featured_media":32423,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[37],"tags":[],"class_list":["post-32422","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-trancoso"],"_links":{"self":[{"href":"https:\/\/sientetupasion.com\/index.php\/wp-json\/wp\/v2\/posts\/32422","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sientetupasion.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sientetupasion.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sientetupasion.com\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/sientetupasion.com\/index.php\/wp-json\/wp\/v2\/comments?post=32422"}],"version-history":[{"count":1,"href":"https:\/\/sientetupasion.com\/index.php\/wp-json\/wp\/v2\/posts\/32422\/revisions"}],"predecessor-version":[{"id":32424,"href":"https:\/\/sientetupasion.com\/index.php\/wp-json\/wp\/v2\/posts\/32422\/revisions\/32424"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sientetupasion.com\/index.php\/wp-json\/wp\/v2\/media\/32423"}],"wp:attachment":[{"href":"https:\/\/sientetupasion.com\/index.php\/wp-json\/wp\/v2\/media?parent=32422"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sientetupasion.com\/index.php\/wp-json\/wp\/v2\/categories?post=32422"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sientetupasion.com\/index.php\/wp-json\/wp\/v2\/tags?post=32422"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}