{"id":32416,"date":"2026-07-14T20:48:39","date_gmt":"2026-07-15T02:48:39","guid":{"rendered":"https:\/\/sientetupasion.com\/?p=32416"},"modified":"2026-07-14T20:48:39","modified_gmt":"2026-07-15T02:48:39","slug":"gobierno-de-rio-grande-acompana-graduacion-de-408-estudiantes-del-cbta-no-20","status":"publish","type":"post","link":"https:\/\/sientetupasion.com\/index.php\/2026\/07\/14\/gobierno-de-rio-grande-acompana-graduacion-de-408-estudiantes-del-cbta-no-20\/","title":{"rendered":"Gobierno de R\u00edo Grande acompa\u00f1a graduaci\u00f3n de 408 estudiantes del CBTA No. 20"},"content":{"rendered":"<h1><\/h1>\n<p class=\"isSelectedEnd\"><strong>R\u00edo Grande, Zacatecas.<\/strong> El Gobierno Municipal de R\u00edo Grande particip\u00f3 en la ceremonia de graduaci\u00f3n del <strong>Centro de Bachillerato Tecnol\u00f3gico Agropecuario No. 20 (CBTA 20)<\/strong>, donde <strong>408 alumnas y alumnos<\/strong> concluyeron satisfactoriamente su educaci\u00f3n media superior en las diferentes carreras que ofrece la instituci\u00f3n.<\/p>\n<p class=\"isSelectedEnd\">La generaci\u00f3n <strong>2023\u20132026<\/strong>, que llev\u00f3 por nombre <strong>\u201cMtro. Jorge Enrique Quirino Perales\u201d<\/strong>, fue reconocida por culminar una importante etapa de su formaci\u00f3n acad\u00e9mica, en un acto que reuni\u00f3 a estudiantes, familias, docentes y autoridades educativas para celebrar este significativo logro.<\/p>\n<p class=\"isSelectedEnd\">En representaci\u00f3n del presidente municipal, <strong>Mario C\u00f3rdova Longoria<\/strong>, asisti\u00f3 el <strong>secretario de Gobierno Municipal, Jes\u00fas Salvador Rosales Mares<\/strong>, quien felicit\u00f3 a las y los egresados por la constancia y dedicaci\u00f3n demostradas durante su trayectoria escolar, destacando que la educaci\u00f3n es la mejor herramienta para construir un futuro con mayores oportunidades.<\/p>\n<p class=\"isSelectedEnd\">Asimismo, reconoci\u00f3 el compromiso del personal docente y administrativo del CBTA No. 20, as\u00ed como el respaldo permanente de madres y padres de familia, cuyo acompa\u00f1amiento fue fundamental para que las y los j\u00f3venes alcanzaran esta meta.<\/p>\n<p class=\"isSelectedEnd\">Durante la ceremonia tambi\u00e9n se rindi\u00f3 homenaje al <strong>Mtro. Jorge Enrique Quirino Perales<\/strong>, cuyo nombre distingui\u00f3 a la generaci\u00f3n como reconocimiento a su trayectoria y aportaciones en favor de la educaci\u00f3n.<\/p>\n<p>Con su participaci\u00f3n en este acto acad\u00e9mico, el Gobierno Municipal de R\u00edo Grande reiter\u00f3 su compromiso con el fortalecimiento de la educaci\u00f3n y con el impulso de acciones que permitan a las nuevas generaciones desarrollar su talento y contribuir al progreso del municipio y del estado.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>R\u00edo Grande, Zacatecas. El Gobierno Municipal de R\u00edo Grande particip\u00f3 en la ceremonia de graduaci\u00f3n del Centro de Bachillerato Tecnol\u00f3gico Agropecuario No. 20 (CBTA 20), donde<span class=\"excerpt-hellip\"> [\u2026]<\/span><\/p>\n","protected":false},"author":2,"featured_media":32417,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[41],"tags":[],"class_list":["post-32416","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-rio-grande"],"_links":{"self":[{"href":"https:\/\/sientetupasion.com\/index.php\/wp-json\/wp\/v2\/posts\/32416","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sientetupasion.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sientetupasion.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sientetupasion.com\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/sientetupasion.com\/index.php\/wp-json\/wp\/v2\/comments?post=32416"}],"version-history":[{"count":1,"href":"https:\/\/sientetupasion.com\/index.php\/wp-json\/wp\/v2\/posts\/32416\/revisions"}],"predecessor-version":[{"id":32418,"href":"https:\/\/sientetupasion.com\/index.php\/wp-json\/wp\/v2\/posts\/32416\/revisions\/32418"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sientetupasion.com\/index.php\/wp-json\/wp\/v2\/media\/32417"}],"wp:attachment":[{"href":"https:\/\/sientetupasion.com\/index.php\/wp-json\/wp\/v2\/media?parent=32416"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sientetupasion.com\/index.php\/wp-json\/wp\/v2\/categories?post=32416"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sientetupasion.com\/index.php\/wp-json\/wp\/v2\/tags?post=32416"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}