{"id":26178,"date":"2026-03-26T11:34:52","date_gmt":"2026-03-26T17:34:52","guid":{"rendered":"https:\/\/sientetupasion.com\/?p=26178"},"modified":"2026-03-26T11:35:00","modified_gmt":"2026-03-26T17:35:00","slug":"dif-capital-impulsa-autoempleo-con-encuentro-de-saberes-y-sabores-en-cieneguillas","status":"publish","type":"post","link":"https:\/\/sientetupasion.com\/index.php\/2026\/03\/26\/dif-capital-impulsa-autoempleo-con-encuentro-de-saberes-y-sabores-en-cieneguillas\/","title":{"rendered":"DIF Capital impulsa autoempleo con \u201cEncuentro de saberes y sabores\u201d en Cieneguillas"},"content":{"rendered":"\n<p>\u2022\tCon la finalidad de crear proyectos productivos que impulsen el desarrollo en las comunidades y fortalezcan la econom\u00eda en las familias capitalinas.<br \/>\n\u2022\tUn intercambio de tradiciones, gastronom\u00eda, costumbres y cultura, entre las mujeres de la zona urbana y rural.<\/p>\n<p>Zacatecas, Zac.- La Presidenta Honor\u00edfica de DIF municipal Zacatecas, Karla Estrada, encabez\u00f3 el Encuentro de Saberes y Sabores, que se realiz\u00f3 en la comunidad de Cieneguillas, esto como parte de las actividades conmemorativas al D\u00eda Internacional de la Mujer.<\/p>\n<p>Durante este encuentro participaron beneficiarias de Inclusi\u00f3n, integrantes de los centros sociales Bellavista y CNOP, as\u00ed como tambi\u00e9n las comunidades de El Maguey y Cieneguillas.<\/p>\n<p>Por su parte, Karla Estrada expres\u00f3 sentirse muy contenta de compartir de este intercambio cultural con mujeres de la capital y comunidades, \u201cporque podemos tener una convivencia sana, conocer y aprender costumbres, platillos y tradiciones de otros lugares; e intercambiar ideas que nos permitan impulsar el desarrollo social, econ\u00f3mico o familiar desde cada uno de nuestros lugares\u201d.<\/p>\n<p>Las mujeres participaron en una capacitaci\u00f3n de huertos comunitarios, en este sentido Mar\u00eda del Rosario Ortiz Acu\u00f1a, enlace Rural de DIF capital, explic\u00f3 que este es el primer programa piloto de huertos comunitarios elaborado por mujeres.<\/p>\n<p>Asimismo, participaron en una activaci\u00f3n f\u00edsica y elaboraron exquisitos platillos, ensaladas, postres y aguas frescas para compartir durante un agradable convivio.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u2022 Con la finalidad de crear proyectos productivos que impulsen el desarrollo en las comunidades y fortalezcan la econom\u00eda en las familias capitalinas. \u2022 Un intercambio<span class=\"excerpt-hellip\"> [\u2026]<\/span><\/p>\n","protected":false},"author":2,"featured_media":26179,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[],"class_list":["post-26178","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-locales"],"_links":{"self":[{"href":"https:\/\/sientetupasion.com\/index.php\/wp-json\/wp\/v2\/posts\/26178","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sientetupasion.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sientetupasion.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sientetupasion.com\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/sientetupasion.com\/index.php\/wp-json\/wp\/v2\/comments?post=26178"}],"version-history":[{"count":1,"href":"https:\/\/sientetupasion.com\/index.php\/wp-json\/wp\/v2\/posts\/26178\/revisions"}],"predecessor-version":[{"id":26180,"href":"https:\/\/sientetupasion.com\/index.php\/wp-json\/wp\/v2\/posts\/26178\/revisions\/26180"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sientetupasion.com\/index.php\/wp-json\/wp\/v2\/media\/26179"}],"wp:attachment":[{"href":"https:\/\/sientetupasion.com\/index.php\/wp-json\/wp\/v2\/media?parent=26178"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sientetupasion.com\/index.php\/wp-json\/wp\/v2\/categories?post=26178"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sientetupasion.com\/index.php\/wp-json\/wp\/v2\/tags?post=26178"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}